{"id":37390,"date":"2022-05-10T19:48:52","date_gmt":"2022-05-10T17:48:52","guid":{"rendered":"https:\/\/nuvobarcelona.com\/?post_type=property&#038;p=37390"},"modified":"2022-12-08T12:02:18","modified_gmt":"2022-12-08T10:02:18","slug":"cartagena-230-local-1","status":"publish","type":"property","link":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/","title":{"rendered":"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona"},"content":{"rendered":"<p>[et_pb_section fb_built=\"1\" _builder_version=\"4.16\" _module_preset=\"default\" custom_padding=\"0px|0px|0px|0px|false|false\" da_disable_devices=\"off|off|off\" global_colors_info=\"{}\" da_is_popup=\"off\" da_exit_intent=\"off\" da_has_close=\"on\" da_alt_close=\"off\" da_dark_close=\"off\" da_not_modal=\"on\" da_is_singular=\"off\" da_with_loader=\"off\" da_has_shadow=\"on\"][et_pb_row _builder_version=\"4.16\" _module_preset=\"default\" custom_margin=\"||0px||false|false\" custom_padding=\"20px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"]<a style=\"text-decoration:none; color:red;\" href=\"\/ca\/vivendes_en_venda\/\"><i class=\"fas fa-arrow-left\"><\/i> Torna a la llista de propietats<\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" custom_padding_last_edited=\"on|phone\" _builder_version=\"4.16\" custom_margin_tablet=\"\" custom_margin_phone=\"||||false|false\" custom_margin_last_edited=\"on|phone\" custom_padding=\"50px||50px||false|false\" custom_padding_tablet=\"\" custom_padding_phone=\"5%||5%||false|false\" da_disable_devices=\"off|off|off\" global_colors_info=\"{}\" da_is_popup=\"off\" da_exit_intent=\"off\" da_has_close=\"on\" da_alt_close=\"off\" da_dark_close=\"off\" da_not_modal=\"on\" da_is_singular=\"off\" da_with_loader=\"off\" da_has_shadow=\"on\"][et_pb_row custom_padding_last_edited=\"on|desktop\" module_class=\"nb-downloads-section\" _builder_version=\"4.16\" width=\"90%\" custom_margin=\"0px||50px||false|false\" custom_margin_tablet=\"\" custom_margin_phone=\"0px||5%||false|false\" custom_margin_last_edited=\"on|phone\" custom_padding=\"0px||0px||false|false\" custom_padding_tablet=\"\" custom_padding_phone=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_text admin_label=\"Description\" _builder_version=\"4.16\" _dynamic_attributes=\"content\" custom_margin=\"||0px||false|false\" custom_margin_tablet=\"\" custom_margin_phone=\"||0px||false|false\" custom_margin_last_edited=\"on|desktop\" global_colors_info=\"{}\"]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfcHJvcGVydHlfZGVzY3JpcHRpb24iLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiIiLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib24ifX0=@[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\"on|phone\" _builder_version=\"4.16\" width=\"90%\" custom_padding=\"0px||50px||false|false\" custom_padding_tablet=\"\" custom_padding_phone=\"||5%||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_gallery gallery_ids=\"37385,37373,37369,37365,37361,37357\" fullwidth=\"on\" _builder_version=\"4.17.3\" custom_margin_tablet=\"\" custom_margin_phone=\"||0px||false|false\" custom_margin_last_edited=\"on|desktop\" custom_padding=\"||0px||false|false\" custom_css_gallery_item=\"-webkit-animation: none !important;||-moz-animation: none !important;||-o-animation: none !important;||-ms-animation: none !important;||animation: none !important;\" locked=\"off\" global_colors_info=\"{}\"][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\"1_2,1_2\" use_custom_gutter=\"on\" gutter_width=\"2\" make_equal=\"on\" custom_padding_last_edited=\"on|desktop\" module_class=\"nb_call_to_actions_container\" _builder_version=\"4.16\" width=\"90%\" custom_margin=\"||0px||false|false\" custom_margin_tablet=\"\" custom_margin_phone=\"0px||||false|false\" custom_margin_last_edited=\"on|phone\" custom_padding=\"0px||0px||false|false\" custom_padding_tablet=\"\" custom_padding_phone=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"1_2\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_cta button_url=\"@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfcHJvcGVydHlfc2FsZXNfcGxhbnMiLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiIiLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib2ZmIn19@\" url_new_window=\"on\" button_text=\"Descarregar\" admin_label=\"Sales Plans\" module_class=\"nb_call_to_action\" _builder_version=\"4.16\" _dynamic_attributes=\"button_url\" body_font=\"|700|||||||\" body_font_size=\"16px\" body_line_height=\"1.3em\" background_color=\"#323435\" custom_button=\"on\" button_text_size=\"18px\" button_border_width=\"2px\" button_border_radius=\"19px\" button_font=\"|600|||||||\" button_use_icon=\"off\" width=\"100%\" max_width=\"100%\" custom_margin=\"||||false|false\" custom_padding=\"35px|35px|35px|35px|true|true\" custom_css_main_element=\"||\" border_radii=\"off|8px|8px|8px|8px\" global_colors_info=\"{}\"]PL\u00c0NOLS[\/et_pb_cta][\/et_pb_column][et_pb_column type=\"1_2\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_cta button_url=\"@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VzdG9tX21ldGFfcHJvcGVydHlfZW5lcmd5X3F1YWxpZmljYXRpb24iLCJzZXR0aW5ncyI6eyJiZWZvcmUiOiIiLCJhZnRlciI6IiIsImVuYWJsZV9odG1sIjoib2ZmIn19@\" url_new_window=\"on\" button_text=\"Descarregar\" admin_label=\"Energy Qualification\" module_class=\"nb_call_to_action\" _builder_version=\"4.16\" _dynamic_attributes=\"button_url\" body_font=\"|700|||||||\" body_font_size=\"16px\" body_line_height=\"1.3em\" background_color=\"#323435\" custom_button=\"on\" button_text_size=\"18px\" button_border_width=\"2px\" button_border_radius=\"19px\" button_font=\"|600|||||||\" button_use_icon=\"off\" width=\"100%\" max_width=\"100%\" custom_padding=\"35px|35px|35px|35px|true|true\" custom_css_main_element=\"||\" border_radii=\"off|8px|8px|8px|8px\" locked=\"off\" global_colors_info=\"{}\"]<\/p>\n<p>QUALIFICACI\u00d3 ENERG\u00c8TICA<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.16\" _module_preset=\"default\" custom_padding=\"0px||20px||false|false\" da_disable_devices=\"off|off|off\" saved_tabs=\"all\" global_colors_info=\"{}\" da_is_popup=\"off\" da_exit_intent=\"off\" da_has_close=\"on\" da_alt_close=\"off\" da_dark_close=\"off\" da_not_modal=\"on\" da_is_singular=\"off\" da_with_loader=\"off\" da_has_shadow=\"on\"][et_pb_row _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_button button_url=\"#bttncontactpopup\" button_text=\"Contacti'ns\" button_alignment=\"center\" button_text_tablet=\"Contacti'ns\" button_text_phone=\"Contacti'ns\" button_text_last_edited=\"on|desktop\" module_id=\"bttncontact\" _builder_version=\"4.16\" _module_preset=\"default\" custom_button=\"on\" button_text_size=\"20px\" button_text_color=\"#ffffff\" button_bg_color=\"#242424\" button_bg_use_color_gradient=\"on\" button_bg_color_gradient_direction=\"0deg\" button_bg_color_gradient_stops=\"#000000 0%|#000000 100%\" button_bg_color_gradient_start=\"#000000\" button_bg_color_gradient_end=\"#000000\" button_border_width=\"0px\" button_border_radius=\"16px\" button_font=\"|700|||||||\" background_layout=\"dark\" custom_margin=\"0px||0px||false|false\" custom_padding=\"5px||5px||false|false\" global_colors_info=\"{}\"][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"Popup - #bttncontactpopup\" module_id=\"bttncontactpopup\" module_class=\"popup\" _builder_version=\"4.6.1\" background_color=\"rgba(0,0,0,0)\" custom_margin=\"0px||0px||false|false\" custom_padding=\"0px||0px||false|false\" da_is_popup=\"on\" da_popup_slug=\"bttncontactpopup\" da_disable_devices=\"off|off|off\" global_module=\"22735\" global_colors_info=\"{}\" da_exit_intent=\"off\" da_has_close=\"on\" da_alt_close=\"off\" da_dark_close=\"off\" da_not_modal=\"on\" da_is_singular=\"off\" da_with_loader=\"off\" da_has_shadow=\"on\"][et_pb_row column_structure=\"1_5,3_5,1_5\" module_class=\"pu-row\" _builder_version=\"4.16\" background_color=\"#dadada\" use_background_color_gradient=\"on\" background_color_gradient_stops=\"rgba(46,60,66,0.43) 0%|rgba(157,196,189,0.65) 100%\" background_color_gradient_start=\"rgba(46,60,66,0.43)\" background_color_gradient_end=\"rgba(157,196,189,0.65)\" width=\"100%\" custom_margin=\"||0px||false|false\" custom_padding=\"50px|0px|50px|0px|false|true\" global_colors_info=\"{}\"][et_pb_column type=\"1_5\" module_class=\"first-col\" _builder_version=\"4.16\" global_colors_info=\"{}\"][\/et_pb_column][et_pb_column type=\"3_5\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.16\" _module_preset=\"default\" global_colors_info=\"{}\"]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f35464-o1\" lang=\"ca-ES\" dir=\"ltr\" data-wpcf7-id=\"35464\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/property\/37390#wpcf7-f35464-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"35464\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f35464-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/fieldset>\n<div class=\"form_ttl\">\n\t<h2>Contacta amb nosaltres\n\t<\/h2>\n<\/div>\n<p><label> El teu nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label><br \/>\n<label> El teu email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><br \/>\n<label> El seu n\u00famero de tel\u00e8fon<br \/>\n<span class=\"wpcf7-form-control-wrap tel\"><input class=\"wpcf7-form-control wpcf7-intl_tel wpcf7-validates-as-required wpcf7-intl-tel phonenum\" aria-required=\"true\" aria-invalid=\"false\" data-initialcountry=\"es\" data-preferredcountries=\"fr-gb-us-es\" value=\"\" type=\"tel\" name=\"tel-cf7it-national\" \/><input name=\"tel\" type=\"hidden\" class=\"wpcf7-intl-tel-full\" \/><input type=\"hidden\" name=\"tel-cf7it-country-name\" class=\"wpcf7-intl-tel-country-name\" \/><input type=\"hidden\" name=\"tel-cf7it-country-code\" class=\"wpcf7-intl-tel-country-code\" \/><input type=\"hidden\" name=\"tel-cf7it-country-iso2\" class=\"wpcf7-intl-tel-country-iso2\" \/><\/span> <\/label><br \/>\n<label> El teu missatge (opcional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label><br \/>\n<span id=\"wpcf7-6a570d5fd9a2a-wrapper\" class=\"wpcf7-form-control-wrap nuvo-681-wrap\" data-cf7apps-honeypot=\"nuvo-681\" style=\"display: block;\n\t\t    width: 0px;\n\t\t    height: 0px;\n\t\t    padding: 0px;\n\t\t    border: 1px solid transparent;\n\t\t    display: block;\n\t\t    overflow: hidden;\n\t\t    \"><input type=\"hidden\" name=\"nuvo-681-random-hash\" value=\"81666755\"><label\n\t\t    for=\"wpcf7-6a570d5fd9a2a-field\"\n\t\t    class=\"hp-message\"\n        >Please leave this field empty.<\/label><input\n\t    id=\"wpcf7-6a570d5fd9a2a-field\"\n\t     placeholder=\"id\" \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"75fyg7hcs5gp\"\n\t    value=\"\"\n\t    size=\"40\"\n\t    autocomplete=\"off\"\n\t    tabindex=\"1000\"\n    \/><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/><br \/>\n<span class=\"wpcf7-form-control-wrap ref\" data-name=\"ref\"><input type=\"hidden\" name=\"ref\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_content\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_term\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gclid\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"246\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=\"1_5\" _builder_version=\"4.16\" global_colors_info=\"{}\"][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.16\" width=\"100%\" custom_margin=\"0px||0px||false|false\" custom_padding=\"0px||0px||false|false\" da_disable_devices=\"off|off|off\" global_colors_info=\"{}\" da_is_popup=\"off\" da_exit_intent=\"off\" da_has_close=\"on\" da_alt_close=\"off\" da_dark_close=\"off\" da_not_modal=\"on\" da_is_singular=\"off\" da_with_loader=\"off\" da_has_shadow=\"on\"][et_pb_row _builder_version=\"4.16\" width=\"100%\" max_width=\"none\" custom_margin=\"0px||0px||false|false\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" global_colors_info=\"{}\"][et_pb_code admin_label=\"Google Maps (Code)\" _builder_version=\"4.16\" custom_margin=\"0px||0px||false|false\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\"][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"featured_media":37286,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"propertie_type":[372,102],"property_tag":[140],"wf_property_folders":[],"class_list":["post-37390","property","type-property","status-publish","has-post-thumbnail","hentry","propertie_type-barcelona-ca","propertie_type-venda","property_tag-vengut"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona\" \/>\n<meta property=\"og:description\" content=\"Torna a la llista de propietatsPL\u00c0NOLSQUALIFICACI\u00d3 ENERG\u00c8TICA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/\" \/>\n<meta property=\"og:site_name\" content=\"NuvoBarcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nuvobarcelona\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-08T10:02:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2022\/05\/IMG_2921-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NuvoBarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/\",\"url\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/\",\"name\":\"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuvobarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_2921-scaled.jpg\",\"datePublished\":\"2022-05-10T17:48:52+00:00\",\"dateModified\":\"2022-12-08T10:02:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuvobarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_2921-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nuvobarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_2921-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/property\\\/cartagena-230-local-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/\",\"name\":\"NuvoBarcelona\",\"description\":\"Living is all about experience\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#organization\",\"name\":\"NuvoBarcelona\",\"url\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nuvobarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NuvoBarcelonaLog.png\",\"contentUrl\":\"https:\\\/\\\/nuvobarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/NuvoBarcelonaLog.png\",\"width\":1207,\"height\":148,\"caption\":\"NuvoBarcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/nuvobarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nuvobarcelona\\\/\",\"https:\\\/\\\/x.com\\\/NuvoBarcelona\",\"https:\\\/\\\/www.instagram.com\\\/nuvobarcelona\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nuvobarcelona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2vGTQCQvwuiOOD_T7v8pIQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/","og_locale":"ca_ES","og_type":"article","og_title":"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona","og_description":"Torna a la llista de propietatsPL\u00c0NOLSQUALIFICACI\u00d3 ENERG\u00c8TICA","og_url":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/","og_site_name":"NuvoBarcelona","article_publisher":"https:\/\/www.facebook.com\/nuvobarcelona\/","article_modified_time":"2022-12-08T10:02:18+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2022\/05\/IMG_2921-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@NuvoBarcelona","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/","url":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/","name":"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona - NuvoBarcelona","isPartOf":{"@id":"https:\/\/nuvobarcelona.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/#primaryimage"},"image":{"@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/#primaryimage"},"thumbnailUrl":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2022\/05\/IMG_2921-scaled.jpg","datePublished":"2022-05-10T17:48:52+00:00","dateModified":"2022-12-08T10:02:18+00:00","breadcrumb":{"@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/#primaryimage","url":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2022\/05\/IMG_2921-scaled.jpg","contentUrl":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2022\/05\/IMG_2921-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/nuvobarcelona.com\/ca\/property\/cartagena-230-local-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuvobarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Cartagena 230, Local Comercial en venda d\u00b4obra nova a Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/nuvobarcelona.com\/ca\/#website","url":"https:\/\/nuvobarcelona.com\/ca\/","name":"NuvoBarcelona","description":"Living is all about experience","publisher":{"@id":"https:\/\/nuvobarcelona.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuvobarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/nuvobarcelona.com\/ca\/#organization","name":"NuvoBarcelona","url":"https:\/\/nuvobarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/nuvobarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2020\/08\/NuvoBarcelonaLog.png","contentUrl":"https:\/\/nuvobarcelona.com\/wp-content\/uploads\/2020\/08\/NuvoBarcelonaLog.png","width":1207,"height":148,"caption":"NuvoBarcelona"},"image":{"@id":"https:\/\/nuvobarcelona.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nuvobarcelona\/","https:\/\/x.com\/NuvoBarcelona","https:\/\/www.instagram.com\/nuvobarcelona\/?hl=en","https:\/\/www.linkedin.com\/company\/nuvobarcelona\/","https:\/\/www.youtube.com\/channel\/UC2vGTQCQvwuiOOD_T7v8pIQ"]}]}},"_links":{"self":[{"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/property\/37390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/types\/property"}],"version-history":[{"count":1,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/property\/37390\/revisions"}],"predecessor-version":[{"id":40690,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/property\/37390\/revisions\/40690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/media\/37286"}],"wp:attachment":[{"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=37390"}],"wp:term":[{"taxonomy":"propertie_type","embeddable":true,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/propertie_type?post=37390"},{"taxonomy":"property_tag","embeddable":true,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/property_tag?post=37390"},{"taxonomy":"wf_property_folders","embeddable":true,"href":"https:\/\/nuvobarcelona.com\/ca\/wp-json\/wp\/v2\/wf_property_folders?post=37390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}